{"id":1683,"count":1,"description":"","link":"https:\/\/iafrika.org\/tn\/tag\/kgosi-molefi-molefe\/","name":"Kgosi Molefi Molefe","slug":"kgosi-molefi-molefe","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kgosi Molefi Molefe Archives - iAfrika - Setswana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iafrika.org\/tn\/tag\/kgosi-molefi-molefe\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kgosi Molefi Molefe Archives - iAfrika - Setswana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iafrika.org\/tn\/tag\/kgosi-molefi-molefe\/\" \/>\n<meta property=\"og:site_name\" content=\"iAfrika - Setswana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/tag\\\/kgosi-molefi-molefe\\\/\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/tag\\\/kgosi-molefi-molefe\\\/\",\"name\":\"Kgosi Molefi Molefe Archives - iAfrika - Setswana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/tag\\\/kgosi-molefi-molefe\\\/#breadcrumb\"},\"inLanguage\":\"en-ZA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/tag\\\/kgosi-molefi-molefe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kgosi Molefi Molefe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#website\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/\",\"name\":\"iAfrika - Setswana\",\"description\":\"Tlhaloso ya Ditoro, Maele le diane, Dipoko tsa losika le difane\",\"publisher\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-ZA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#organization\",\"name\":\"iAfrika - Setswana\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-ZA\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/Fullform_Logo_Primary.png\",\"contentUrl\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/Fullform_Logo_Primary.png\",\"width\":800,\"height\":296,\"caption\":\"iAfrika - Setswana\"},\"image\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kgosi Molefi Molefe Archives - iAfrika - Setswana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iafrika.org\/tn\/tag\/kgosi-molefi-molefe\/","og_locale":"en_US","og_type":"article","og_title":"Kgosi Molefi Molefe Archives - iAfrika - Setswana","og_url":"https:\/\/iafrika.org\/tn\/tag\/kgosi-molefi-molefe\/","og_site_name":"iAfrika - Setswana","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/iafrika.org\/tn\/tag\/kgosi-molefi-molefe\/","url":"https:\/\/iafrika.org\/tn\/tag\/kgosi-molefi-molefe\/","name":"Kgosi Molefi Molefe Archives - iAfrika - Setswana","isPartOf":{"@id":"https:\/\/iafrika.org\/tn\/#website"},"breadcrumb":{"@id":"https:\/\/iafrika.org\/tn\/tag\/kgosi-molefi-molefe\/#breadcrumb"},"inLanguage":"en-ZA"},{"@type":"BreadcrumbList","@id":"https:\/\/iafrika.org\/tn\/tag\/kgosi-molefi-molefe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/iafrika.org\/tn\/"},{"@type":"ListItem","position":2,"name":"Kgosi Molefi Molefe"}]},{"@type":"WebSite","@id":"https:\/\/iafrika.org\/tn\/#website","url":"https:\/\/iafrika.org\/tn\/","name":"iAfrika - Setswana","description":"Tlhaloso ya Ditoro, Maele le diane, Dipoko tsa losika le difane","publisher":{"@id":"https:\/\/iafrika.org\/tn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iafrika.org\/tn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-ZA"},{"@type":"Organization","@id":"https:\/\/iafrika.org\/tn\/#organization","name":"iAfrika - Setswana","url":"https:\/\/iafrika.org\/tn\/","logo":{"@type":"ImageObject","inLanguage":"en-ZA","@id":"https:\/\/iafrika.org\/tn\/#\/schema\/logo\/image\/","url":"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/02\/Fullform_Logo_Primary.png","contentUrl":"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/02\/Fullform_Logo_Primary.png","width":800,"height":296,"caption":"iAfrika - Setswana"},"image":{"@id":"https:\/\/iafrika.org\/tn\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/tags\/1683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/posts?tags=1683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}