{"id":785,"date":"2022-01-31T17:58:13","date_gmt":"2022-01-31T15:58:13","guid":{"rendered":"https:\/\/iafrika.org\/tn\/?p=785"},"modified":"2023-10-01T09:34:44","modified_gmt":"2023-10-01T07:34:44","slug":"ditoro-ka-ga-folouru","status":"publish","type":"post","link":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-folouru\/","title":{"rendered":"Ditoro ka ga folouru"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/flour-2-1-1024x1024.jpg\" alt=\"\" class=\"wp-image-848\" srcset=\"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/flour-2-1-1024x1024.jpg 1024w, https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/flour-2-1-300x300.jpg 300w, https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/flour-2-1-150x150.jpg 150w, https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/flour-2-1-768x768.jpg 768w, https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/flour-2-1.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Fa o lora folouru, go raya gore o tlile go tlhaselwa ke bolwetse kgotsa leso lo tla tlhasela lapa la gago gautshwana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fa o lora folouru, go raya gore o tlile go tlhaselwa ke bolwetse kgotsa leso lo tla tlhasela lapa la gago gautshwana.<\/p>\n","protected":false},"author":139,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1641],"tags":[507],"class_list":["post-785","post","type-post","status-publish","format-standard","hentry","category-tlhaloso-ya-ditoro","tag-folouru"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ditoro ka ga folouru - iAfrika - Setswana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-folouru\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ditoro ka ga folouru - iAfrika - Setswana\" \/>\n<meta property=\"og:description\" content=\"Fa o lora folouru, go raya gore o tlile go tlhaselwa ke bolwetse kgotsa leso lo tla tlhasela lapa la gago gautshwana.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-folouru\/\" \/>\n<meta property=\"og:site_name\" content=\"iAfrika - Setswana\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-31T15:58:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-01T07:34:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/flour-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"iAfrika\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"iAfrika\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-folouru\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-folouru\\\/\"},\"author\":{\"name\":\"iAfrika\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#\\\/schema\\\/person\\\/55a0587c04707bb054363ee4f50541bb\"},\"headline\":\"Ditoro ka ga folouru\",\"datePublished\":\"2022-01-31T15:58:13+00:00\",\"dateModified\":\"2023-10-01T07:34:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-folouru\\\/\"},\"wordCount\":26,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-folouru\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/flour-2-1-1024x1024.jpg\",\"keywords\":[\"Folouru\"],\"articleSection\":[\"Tlhaloso ya Ditoro\"],\"inLanguage\":\"en-ZA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-folouru\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-folouru\\\/\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-folouru\\\/\",\"name\":\"Ditoro ka ga folouru - iAfrika - Setswana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-folouru\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-folouru\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/flour-2-1-1024x1024.jpg\",\"datePublished\":\"2022-01-31T15:58:13+00:00\",\"dateModified\":\"2023-10-01T07:34:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-folouru\\\/#breadcrumb\"},\"inLanguage\":\"en-ZA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-folouru\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-ZA\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-folouru\\\/#primaryimage\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/flour-2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/flour-2-1.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-folouru\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ditoro ka ga folouru\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#website\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/\",\"name\":\"iAfrika - Setswana\",\"description\":\"Tlhaloso ya Ditoro, Maele le diane, Dipoko tsa losika le difane\",\"publisher\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-ZA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#organization\",\"name\":\"iAfrika - Setswana\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-ZA\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/Fullform_Logo_Primary.png\",\"contentUrl\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/Fullform_Logo_Primary.png\",\"width\":800,\"height\":296,\"caption\":\"iAfrika - Setswana\"},\"image\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#\\\/schema\\\/person\\\/55a0587c04707bb054363ee4f50541bb\",\"name\":\"iAfrika\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-ZA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e14e935f8a006378fd964349e3062a0d752068ce7b225a31c446f0d96468dc55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e14e935f8a006378fd964349e3062a0d752068ce7b225a31c446f0d96468dc55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e14e935f8a006378fd964349e3062a0d752068ce7b225a31c446f0d96468dc55?s=96&d=mm&r=g\",\"caption\":\"iAfrika\"},\"description\":\"Amaphupho, Amasiko, Izithakazelo, Umlando ngesiZulu. Amaphupha ngesiXhosa: https:\\\/\\\/iafrika.org\\\/xh\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/author\\\/iafrika\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ditoro ka ga folouru - iAfrika - Setswana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-folouru\/","og_locale":"en_US","og_type":"article","og_title":"Ditoro ka ga folouru - iAfrika - Setswana","og_description":"Fa o lora folouru, go raya gore o tlile go tlhaselwa ke bolwetse kgotsa leso lo tla tlhasela lapa la gago gautshwana.","og_url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-folouru\/","og_site_name":"iAfrika - Setswana","article_published_time":"2022-01-31T15:58:13+00:00","article_modified_time":"2023-10-01T07:34:44+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/flour-2-1.jpg","type":"image\/jpeg"}],"author":"iAfrika","twitter_card":"summary_large_image","twitter_misc":{"Written by":"iAfrika"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-folouru\/#article","isPartOf":{"@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-folouru\/"},"author":{"name":"iAfrika","@id":"https:\/\/iafrika.org\/tn\/#\/schema\/person\/55a0587c04707bb054363ee4f50541bb"},"headline":"Ditoro ka ga folouru","datePublished":"2022-01-31T15:58:13+00:00","dateModified":"2023-10-01T07:34:44+00:00","mainEntityOfPage":{"@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-folouru\/"},"wordCount":26,"commentCount":0,"publisher":{"@id":"https:\/\/iafrika.org\/tn\/#organization"},"image":{"@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-folouru\/#primaryimage"},"thumbnailUrl":"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/flour-2-1-1024x1024.jpg","keywords":["Folouru"],"articleSection":["Tlhaloso ya Ditoro"],"inLanguage":"en-ZA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/iafrika.org\/tn\/ditoro-ka-ga-folouru\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-folouru\/","url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-folouru\/","name":"Ditoro ka ga folouru - iAfrika - Setswana","isPartOf":{"@id":"https:\/\/iafrika.org\/tn\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-folouru\/#primaryimage"},"image":{"@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-folouru\/#primaryimage"},"thumbnailUrl":"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/flour-2-1-1024x1024.jpg","datePublished":"2022-01-31T15:58:13+00:00","dateModified":"2023-10-01T07:34:44+00:00","breadcrumb":{"@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-folouru\/#breadcrumb"},"inLanguage":"en-ZA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iafrika.org\/tn\/ditoro-ka-ga-folouru\/"]}]},{"@type":"ImageObject","inLanguage":"en-ZA","@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-folouru\/#primaryimage","url":"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/flour-2-1.jpg","contentUrl":"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/flour-2-1.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-folouru\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/iafrika.org\/tn\/"},{"@type":"ListItem","position":2,"name":"Ditoro ka ga folouru"}]},{"@type":"WebSite","@id":"https:\/\/iafrika.org\/tn\/#website","url":"https:\/\/iafrika.org\/tn\/","name":"iAfrika - Setswana","description":"Tlhaloso ya Ditoro, Maele le diane, Dipoko tsa losika le difane","publisher":{"@id":"https:\/\/iafrika.org\/tn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iafrika.org\/tn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-ZA"},{"@type":"Organization","@id":"https:\/\/iafrika.org\/tn\/#organization","name":"iAfrika - Setswana","url":"https:\/\/iafrika.org\/tn\/","logo":{"@type":"ImageObject","inLanguage":"en-ZA","@id":"https:\/\/iafrika.org\/tn\/#\/schema\/logo\/image\/","url":"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/02\/Fullform_Logo_Primary.png","contentUrl":"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/02\/Fullform_Logo_Primary.png","width":800,"height":296,"caption":"iAfrika - Setswana"},"image":{"@id":"https:\/\/iafrika.org\/tn\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/iafrika.org\/tn\/#\/schema\/person\/55a0587c04707bb054363ee4f50541bb","name":"iAfrika","image":{"@type":"ImageObject","inLanguage":"en-ZA","@id":"https:\/\/secure.gravatar.com\/avatar\/e14e935f8a006378fd964349e3062a0d752068ce7b225a31c446f0d96468dc55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e14e935f8a006378fd964349e3062a0d752068ce7b225a31c446f0d96468dc55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e14e935f8a006378fd964349e3062a0d752068ce7b225a31c446f0d96468dc55?s=96&d=mm&r=g","caption":"iAfrika"},"description":"Amaphupho, Amasiko, Izithakazelo, Umlando ngesiZulu. Amaphupha ngesiXhosa: https:\/\/iafrika.org\/xh","url":"https:\/\/iafrika.org\/tn\/author\/iafrika\/"}]}},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":1815,"url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-bolwetse\/","url_meta":{"origin":785,"position":0},"title":"Ditoro ka ga bolwetse","author":"iAfrika","date":"20 May 2023","format":false,"excerpt":"Fa o lora o na le bolwetse, ka tlwaelo go raya gore o tlile go itekanela. Fa o lora o na le bolwetse jo bo itseng go raya gore mongwe yo mongwe yo o tshwereng ke bolwetse joo o tlile go fola. Fa o lora ka bolwetse go ka nna\u2026","rel":"","context":"In &quot;Ditoro ka ga Bolwetse&quot;","block_context":{"text":"Ditoro ka ga Bolwetse","link":"https:\/\/iafrika.org\/tn\/category\/tlhaloso-ya-ditoro\/ditoro-ka-ga-bolwetse\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":203,"url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-leso\/","url_meta":{"origin":785,"position":1},"title":"Ditoro ka ga leso","author":"iAfrika","date":"3 March 2022","format":false,"excerpt":"Fa o lora gore o tlhokafetse, ka tlwaelo se se raya gore o tlile go nna lesego gautshwana.\u00a0O ka...","rel":"","context":"In &quot;Ditoro ka ga leso&quot;","block_context":{"text":"Ditoro ka ga leso","link":"https:\/\/iafrika.org\/tn\/category\/tlhaloso-ya-ditoro\/ditoro-ka-ga-leso\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/1140-fd-smart-ways-cover-costs-funeral.imgcache.rev_.web_.900.518.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/1140-fd-smart-ways-cover-costs-funeral.imgcache.rev_.web_.900.518.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/1140-fd-smart-ways-cover-costs-funeral.imgcache.rev_.web_.900.518.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/1140-fd-smart-ways-cover-costs-funeral.imgcache.rev_.web_.900.518.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2073,"url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-ditoro-ka-ga-motlholagadi\/","url_meta":{"origin":785,"position":2},"title":"Ditoro ka ga ditoro ka ga motlholagadi","author":"iAfrika","date":"20 May 2023","format":false,"excerpt":"Fa o lora motlholagadi, go raya gore mongwe yo o mo ratang o tlile go tlhokafala gaufinyana.","rel":"","context":"In &quot;Ditoro ka ga Batho&quot;","block_context":{"text":"Ditoro ka ga Batho","link":"https:\/\/iafrika.org\/tn\/category\/tlhaloso-ya-ditoro\/ditoro-ka-ga-batho\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":287,"url":"https:\/\/iafrika.org\/tn\/ditoro-ka-go-tlhola-kgotsa-go-fenya\/","url_meta":{"origin":785,"position":3},"title":"Ditoro ka go tlhola kgotsa go fenya","author":"iAfrika","date":"1 March 2022","format":false,"excerpt":"Ditoro ka go tlhola di kaya gore mathata...","rel":"","context":"In &quot;Ditoro ka ga metshameko&quot;","block_context":{"text":"Ditoro ka ga metshameko","link":"https:\/\/iafrika.org\/tn\/category\/tlhaloso-ya-ditoro\/ditoro-ka-ga-metshameko\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2023\/06\/pexels-rdne-stock-project-7005693-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2023\/06\/pexels-rdne-stock-project-7005693-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2023\/06\/pexels-rdne-stock-project-7005693-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1845,"url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-mogolo-o-o-botlhoko\/","url_meta":{"origin":785,"position":4},"title":"Ditoro ka ga mogolo o o botlhoko","author":"iAfrika","date":"20 May 2023","format":false,"excerpt":"Fa o lora mogolo wa gago o le botlhoko, go raya gore o tlile go nna lesego gautshwane.","rel":"","context":"In &quot;Ditoro ka ga Bolwetse&quot;","block_context":{"text":"Ditoro ka ga Bolwetse","link":"https:\/\/iafrika.org\/tn\/category\/tlhaloso-ya-ditoro\/ditoro-ka-ga-bolwetse\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2145,"url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-moletlo-o-o-boitshepo\/","url_meta":{"origin":785,"position":5},"title":"Ditoro ka ga moletlo o o boitshepo","author":"iAfrika","date":"21 May 2023","format":false,"excerpt":"Fa o lora moletlo o o boitshepo, go raya gore gautshwana wa losika la gago o tlile go tlhokafala.","rel":"","context":"In &quot;Ditoro ka ga ditumelo tsa setso&quot;","block_context":{"text":"Ditoro ka ga ditumelo tsa setso","link":"https:\/\/iafrika.org\/tn\/category\/tlhaloso-ya-ditoro\/ditoro-ka-ga-ditumelo-tsa-setso\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/posts\/785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/users\/139"}],"replies":[{"embeddable":true,"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/comments?post=785"}],"version-history":[{"count":4,"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/posts\/785\/revisions"}],"predecessor-version":[{"id":2888,"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/posts\/785\/revisions\/2888"}],"wp:attachment":[{"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/media?parent=785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/categories?post=785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/tags?post=785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}