{"id":661,"date":"2022-02-01T10:58:25","date_gmt":"2022-02-01T08:58:25","guid":{"rendered":"https:\/\/iafrika.org\/tn\/?p=661"},"modified":"2023-10-01T09:20:19","modified_gmt":"2023-10-01T07:20:19","slug":"ditoro-ka-ga-kofi","status":"publish","type":"post","link":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-kofi\/","title":{"rendered":"Ditoro ka ga kofi"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"960\" src=\"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/nathan-dumlao-Y3AqmbmtLQI-unsplash.jpg\" alt=\"\" class=\"wp-image-920\" srcset=\"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/nathan-dumlao-Y3AqmbmtLQI-unsplash.jpg 640w, https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/nathan-dumlao-Y3AqmbmtLQI-unsplash-200x300.jpg 200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Fa o lora ka kofi, go raya gore dilo tse di sa siamang di tlile go direga gautshwana. Gongwe o tlile go iphitlhela fa ntweng kgotsa mongwe yo o mo tshepang o tlile go itsweletsa jaaka motsietsi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fa o lora ka kofi, go raya gore dilo tse di sa siamang di tlile go direga gautshwana. Gongwe o tlile go iphitlhela fa ntweng kgotsa mongwe yo o mo tshepang o tlile go itsweletsa jaaka motsietsi.<\/p>\n","protected":false},"author":139,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1641],"tags":[471],"class_list":["post-661","post","type-post","status-publish","format-standard","hentry","category-tlhaloso-ya-ditoro","tag-kofi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ditoro ka ga kofi - iAfrika - Setswana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-kofi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ditoro ka ga kofi - iAfrika - Setswana\" \/>\n<meta property=\"og:description\" content=\"Fa o lora ka kofi, go raya gore dilo tse di sa siamang di tlile go direga gautshwana. Gongwe o tlile go iphitlhela fa ntweng kgotsa mongwe yo o mo tshepang o tlile go itsweletsa jaaka motsietsi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-kofi\/\" \/>\n<meta property=\"og:site_name\" content=\"iAfrika - Setswana\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-01T08:58:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-01T07:20:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/nathan-dumlao-Y3AqmbmtLQI-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"iAfrika\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"iAfrika\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-kofi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-kofi\\\/\"},\"author\":{\"name\":\"iAfrika\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#\\\/schema\\\/person\\\/55a0587c04707bb054363ee4f50541bb\"},\"headline\":\"Ditoro ka ga kofi\",\"datePublished\":\"2022-02-01T08:58:25+00:00\",\"dateModified\":\"2023-10-01T07:20:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-kofi\\\/\"},\"wordCount\":41,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-kofi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/nathan-dumlao-Y3AqmbmtLQI-unsplash.jpg\",\"keywords\":[\"Kofi\"],\"articleSection\":[\"Tlhaloso ya Ditoro\"],\"inLanguage\":\"en-ZA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-kofi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-kofi\\\/\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-kofi\\\/\",\"name\":\"Ditoro ka ga kofi - iAfrika - Setswana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-kofi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-kofi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/nathan-dumlao-Y3AqmbmtLQI-unsplash.jpg\",\"datePublished\":\"2022-02-01T08:58:25+00:00\",\"dateModified\":\"2023-10-01T07:20:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-kofi\\\/#breadcrumb\"},\"inLanguage\":\"en-ZA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-kofi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-ZA\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-kofi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/nathan-dumlao-Y3AqmbmtLQI-unsplash.jpg\",\"contentUrl\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/nathan-dumlao-Y3AqmbmtLQI-unsplash.jpg\",\"width\":640,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-kofi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ditoro ka ga kofi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#website\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/\",\"name\":\"iAfrika - Setswana\",\"description\":\"Tlhaloso ya Ditoro, Maele le diane, Dipoko tsa losika le difane\",\"publisher\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-ZA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#organization\",\"name\":\"iAfrika - Setswana\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-ZA\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/Fullform_Logo_Primary.png\",\"contentUrl\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/Fullform_Logo_Primary.png\",\"width\":800,\"height\":296,\"caption\":\"iAfrika - Setswana\"},\"image\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#\\\/schema\\\/person\\\/55a0587c04707bb054363ee4f50541bb\",\"name\":\"iAfrika\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-ZA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e14e935f8a006378fd964349e3062a0d752068ce7b225a31c446f0d96468dc55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e14e935f8a006378fd964349e3062a0d752068ce7b225a31c446f0d96468dc55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e14e935f8a006378fd964349e3062a0d752068ce7b225a31c446f0d96468dc55?s=96&d=mm&r=g\",\"caption\":\"iAfrika\"},\"description\":\"Amaphupho, Amasiko, Izithakazelo, Umlando ngesiZulu. Amaphupha ngesiXhosa: https:\\\/\\\/iafrika.org\\\/xh\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/author\\\/iafrika\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ditoro ka ga kofi - iAfrika - Setswana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-kofi\/","og_locale":"en_US","og_type":"article","og_title":"Ditoro ka ga kofi - iAfrika - Setswana","og_description":"Fa o lora ka kofi, go raya gore dilo tse di sa siamang di tlile go direga gautshwana. Gongwe o tlile go iphitlhela fa ntweng kgotsa mongwe yo o mo tshepang o tlile go itsweletsa jaaka motsietsi.","og_url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-kofi\/","og_site_name":"iAfrika - Setswana","article_published_time":"2022-02-01T08:58:25+00:00","article_modified_time":"2023-10-01T07:20:19+00:00","og_image":[{"width":640,"height":960,"url":"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/nathan-dumlao-Y3AqmbmtLQI-unsplash.jpg","type":"image\/jpeg"}],"author":"iAfrika","twitter_card":"summary_large_image","twitter_misc":{"Written by":"iAfrika"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-kofi\/#article","isPartOf":{"@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-kofi\/"},"author":{"name":"iAfrika","@id":"https:\/\/iafrika.org\/tn\/#\/schema\/person\/55a0587c04707bb054363ee4f50541bb"},"headline":"Ditoro ka ga kofi","datePublished":"2022-02-01T08:58:25+00:00","dateModified":"2023-10-01T07:20:19+00:00","mainEntityOfPage":{"@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-kofi\/"},"wordCount":41,"commentCount":0,"publisher":{"@id":"https:\/\/iafrika.org\/tn\/#organization"},"image":{"@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-kofi\/#primaryimage"},"thumbnailUrl":"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/nathan-dumlao-Y3AqmbmtLQI-unsplash.jpg","keywords":["Kofi"],"articleSection":["Tlhaloso ya Ditoro"],"inLanguage":"en-ZA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/iafrika.org\/tn\/ditoro-ka-ga-kofi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-kofi\/","url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-kofi\/","name":"Ditoro ka ga kofi - iAfrika - Setswana","isPartOf":{"@id":"https:\/\/iafrika.org\/tn\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-kofi\/#primaryimage"},"image":{"@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-kofi\/#primaryimage"},"thumbnailUrl":"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/nathan-dumlao-Y3AqmbmtLQI-unsplash.jpg","datePublished":"2022-02-01T08:58:25+00:00","dateModified":"2023-10-01T07:20:19+00:00","breadcrumb":{"@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-kofi\/#breadcrumb"},"inLanguage":"en-ZA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iafrika.org\/tn\/ditoro-ka-ga-kofi\/"]}]},{"@type":"ImageObject","inLanguage":"en-ZA","@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-kofi\/#primaryimage","url":"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/nathan-dumlao-Y3AqmbmtLQI-unsplash.jpg","contentUrl":"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/nathan-dumlao-Y3AqmbmtLQI-unsplash.jpg","width":640,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-kofi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/iafrika.org\/tn\/"},{"@type":"ListItem","position":2,"name":"Ditoro ka ga kofi"}]},{"@type":"WebSite","@id":"https:\/\/iafrika.org\/tn\/#website","url":"https:\/\/iafrika.org\/tn\/","name":"iAfrika - Setswana","description":"Tlhaloso ya Ditoro, Maele le diane, Dipoko tsa losika le difane","publisher":{"@id":"https:\/\/iafrika.org\/tn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iafrika.org\/tn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-ZA"},{"@type":"Organization","@id":"https:\/\/iafrika.org\/tn\/#organization","name":"iAfrika - Setswana","url":"https:\/\/iafrika.org\/tn\/","logo":{"@type":"ImageObject","inLanguage":"en-ZA","@id":"https:\/\/iafrika.org\/tn\/#\/schema\/logo\/image\/","url":"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/02\/Fullform_Logo_Primary.png","contentUrl":"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/02\/Fullform_Logo_Primary.png","width":800,"height":296,"caption":"iAfrika - Setswana"},"image":{"@id":"https:\/\/iafrika.org\/tn\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/iafrika.org\/tn\/#\/schema\/person\/55a0587c04707bb054363ee4f50541bb","name":"iAfrika","image":{"@type":"ImageObject","inLanguage":"en-ZA","@id":"https:\/\/secure.gravatar.com\/avatar\/e14e935f8a006378fd964349e3062a0d752068ce7b225a31c446f0d96468dc55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e14e935f8a006378fd964349e3062a0d752068ce7b225a31c446f0d96468dc55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e14e935f8a006378fd964349e3062a0d752068ce7b225a31c446f0d96468dc55?s=96&d=mm&r=g","caption":"iAfrika"},"description":"Amaphupho, Amasiko, Izithakazelo, Umlando ngesiZulu. Amaphupha ngesiXhosa: https:\/\/iafrika.org\/xh","url":"https:\/\/iafrika.org\/tn\/author\/iafrika\/"}]}},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":198,"url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-dikgotlhang\/","url_meta":{"origin":661,"position":0},"title":"Ditoro ka ga dikgotlhang","author":"iAfrika","date":"3 May 2022","format":false,"excerpt":"Go nale ditoro tse di farologaneng ka ga dikgotlhang tse o ka dilorang. E ka nna...","rel":"","context":"In &quot;Ditoro ka ga dikgotlhang&quot;","block_context":{"text":"Ditoro ka ga dikgotlhang","link":"https:\/\/iafrika.org\/tn\/category\/tlhaloso-ya-ditoro\/ditoro-ka-ga-dikgotlhang\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2023\/06\/pexels-yan-krukau-7640485-4.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2023\/06\/pexels-yan-krukau-7640485-4.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2023\/06\/pexels-yan-krukau-7640485-4.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2023\/06\/pexels-yan-krukau-7640485-4.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2023\/06\/pexels-yan-krukau-7640485-4.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":648,"url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-setlhare\/","url_meta":{"origin":661,"position":1},"title":"Ditoro ka ga setlhare","author":"iAfrika","date":"16 October 2022","format":false,"excerpt":"Fa o ka lora ka ga setlhare, go ka kaya dilo di le dintsi tse di farologaneng. Fa setlhare se le se segolo, ka dikala tse dintsi, go raya gore o tlile go nna le ntlo e kgolo ya bohumi. Fa setlhare se le tala se kgatlhisa, se nonne, kgotsa\u2026","rel":"","context":"In &quot;Ditoro ka ga tikologo, dimela le ditlhare&quot;","block_context":{"text":"Ditoro ka ga tikologo, dimela le ditlhare","link":"https:\/\/iafrika.org\/tn\/category\/tlhaloso-ya-ditoro\/ditoro-ka-ga-tikologo-dimela-le-ditlhare\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2161,"url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-gae\/","url_meta":{"origin":661,"position":2},"title":"Ditoro ka ga gae","author":"iAfrika","date":"21 May 2023","format":false,"excerpt":"Fa o lora ka legae, go kaya dilo tse di farologaneng fa ikaegong ya motho yo o leng ene.\u00a0Fa o le monnye, go raya gore botshelo jwa gago bo tlile go nna monate. Fa o na le mokapelo, go raya gore ba tlile go ikanyega mme le tlile go itumela\u2026","rel":"","context":"In &quot;Ditoro ka ga ntlo&quot;","block_context":{"text":"Ditoro ka ga ntlo","link":"https:\/\/iafrika.org\/tn\/category\/tlhaloso-ya-ditoro\/ditoro-ka-ga-ntlo\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1764,"url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-dinala\/","url_meta":{"origin":661,"position":3},"title":"Ditoro ka ga dinala","author":"iAfrika","date":"20 May 2023","format":false,"excerpt":"Fa o lora ka dinala tsa gago, bokao jwa one bo tla ya ka gore di telele kgotsa di dikhutshwane. Fa o lora ka dinala ditelele, go supa serodumo se sentle mme go raya gore lehumo le fa tseleng. Go botoka thata fa o lora ka monna kgotsa mosadi yo\u2026","rel":"","context":"In &quot;Ditoro ka ga mmele&quot;","block_context":{"text":"Ditoro ka ga mmele","link":"https:\/\/iafrika.org\/tn\/category\/tlhaloso-ya-ditoro\/ditoro-ka-ga-mmele\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2505,"url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-esele\/","url_meta":{"origin":661,"position":4},"title":"Ditoro ka ga esele","author":"iAfrika","date":"22 May 2023","format":false,"excerpt":"Fa o ka lora ka esele, go ka kaya dilo tse dintle kgotsa tse di maswe. Fa o palame esele, go tlile go nna le mathata go isagong ya gago mme batho ba o ntseng o akanya gore o ka ba tshepa ba tlile go go tlogela.\u00a0 Fa esele e\u2026","rel":"","context":"In &quot;Ditoro ka ga diphologolo tsa mo gae le diphologolo tsa balemirui&quot;","block_context":{"text":"Ditoro ka ga diphologolo tsa mo gae le diphologolo tsa balemirui","link":"https:\/\/iafrika.org\/tn\/category\/tlhaloso-ya-ditoro\/ditoro-ka-ga-diphologolo-tsa-mo-gae-le-diphologolo-tsa-balemirui\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2004,"url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-kgaitsadie\/","url_meta":{"origin":661,"position":5},"title":"Ditoro ka ga kgaitsadie","author":"iAfrika","date":"20 May 2023","format":false,"excerpt":"Fa o lora ka ga kgaitsadie, go raya gore go tlile go nna le phetogo fa botshelong jwa gago gautswana. Go ka nna le leso fa lapeng, fela o tlile go tshela botshelo jo bo telele mme dilo di tlile go tokafala morago ga go fetsa go ikilela.","rel":"","context":"In &quot;Ditoro ka ga Balelapa le Losika&quot;","block_context":{"text":"Ditoro ka ga Balelapa le Losika","link":"https:\/\/iafrika.org\/tn\/category\/tlhaloso-ya-ditoro\/ditoro-ka-ga-balelapa-le-losika\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/posts\/661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/users\/139"}],"replies":[{"embeddable":true,"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/comments?post=661"}],"version-history":[{"count":3,"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/posts\/661\/revisions"}],"predecessor-version":[{"id":3276,"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/posts\/661\/revisions\/3276"}],"wp:attachment":[{"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/media?parent=661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/categories?post=661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/tags?post=661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}