{"id":1794,"date":"2023-05-20T14:46:47","date_gmt":"2023-05-20T12:46:47","guid":{"rendered":"https:\/\/iafrika.org\/tn\/?p=1794"},"modified":"2023-09-27T12:23:58","modified_gmt":"2023-09-27T10:23:58","slug":"ditoro-ka-ga-madi-le-go-tswa-madi","status":"publish","type":"post","link":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-madi-le-go-tswa-madi\/","title":{"rendered":"Ditoro ka ga madi le go tswa madi"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Fa o lora o tswa madi lobaka lo lo leele mme o sa itse gore goreng, go raya gore o tlile go nna le bolwetse jo bo masisi tota gautshwane. Fa madi a o a gotlhola, o tlile go iphitlhela o le ntweng gautshwane. Fa o a tlhatsa madi a, le fa go ntse jalo, go raya gore o tlile go nna lesego.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fa o lora o tswa madi lobaka lo lo leele mme o sa itse gore goreng, go raya gore o tlile go nna le bolwetse jo bo masisi tota gautshwane. Fa madi a o a gotlhola, o tlile go iphitlhela o le ntweng gautshwane. Fa o a tlhatsa madi a, le fa go ntse jalo, &#8230; <a title=\"Ditoro ka ga madi le go tswa madi\" class=\"read-more\" href=\"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-madi-le-go-tswa-madi\/\" aria-label=\"Read more about Ditoro ka ga madi le go tswa madi\">Read more<\/a><\/p>\n","protected":false},"author":139,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1648,1641],"tags":[360,1220],"class_list":["post-1794","post","type-post","status-publish","format-standard","hentry","category-ditoro-ka-ga-bolwetse","category-tlhaloso-ya-ditoro","tag-madi","tag-tswa-madi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ditoro ka ga madi le go tswa madi - iAfrika - Setswana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-madi-le-go-tswa-madi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ditoro ka ga madi le go tswa madi - iAfrika - Setswana\" \/>\n<meta property=\"og:description\" content=\"Fa o lora o tswa madi lobaka lo lo leele mme o sa itse gore goreng, go raya gore o tlile go nna le bolwetse jo bo masisi tota gautshwane. Fa madi a o a gotlhola, o tlile go iphitlhela o le ntweng gautshwane. Fa o a tlhatsa madi a, le fa go ntse jalo, ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-madi-le-go-tswa-madi\/\" \/>\n<meta property=\"og:site_name\" content=\"iAfrika - Setswana\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-20T12:46:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-27T10:23:58+00:00\" \/>\n<meta name=\"author\" content=\"iAfrika\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"iAfrika\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-madi-le-go-tswa-madi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-madi-le-go-tswa-madi\\\/\"},\"author\":{\"name\":\"iAfrika\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#\\\/schema\\\/person\\\/55a0587c04707bb054363ee4f50541bb\"},\"headline\":\"Ditoro ka ga madi le go tswa madi\",\"datePublished\":\"2023-05-20T12:46:47+00:00\",\"dateModified\":\"2023-09-27T10:23:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-madi-le-go-tswa-madi\\\/\"},\"wordCount\":71,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#organization\"},\"keywords\":[\"Madi\",\"Tswa madi\"],\"articleSection\":[\"Ditoro ka ga Bolwetse\",\"Tlhaloso ya Ditoro\"],\"inLanguage\":\"en-ZA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-madi-le-go-tswa-madi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-madi-le-go-tswa-madi\\\/\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-madi-le-go-tswa-madi\\\/\",\"name\":\"Ditoro ka ga madi le go tswa madi - iAfrika - Setswana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#website\"},\"datePublished\":\"2023-05-20T12:46:47+00:00\",\"dateModified\":\"2023-09-27T10:23:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-madi-le-go-tswa-madi\\\/#breadcrumb\"},\"inLanguage\":\"en-ZA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-madi-le-go-tswa-madi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/ditoro-ka-ga-madi-le-go-tswa-madi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ditoro ka ga madi le go tswa madi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#website\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/\",\"name\":\"iAfrika - Setswana\",\"description\":\"Tlhaloso ya Ditoro, Maele le diane, Dipoko tsa losika le difane\",\"publisher\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-ZA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#organization\",\"name\":\"iAfrika - Setswana\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-ZA\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/Fullform_Logo_Primary.png\",\"contentUrl\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/Fullform_Logo_Primary.png\",\"width\":800,\"height\":296,\"caption\":\"iAfrika - Setswana\"},\"image\":{\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/#\\\/schema\\\/person\\\/55a0587c04707bb054363ee4f50541bb\",\"name\":\"iAfrika\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-ZA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e14e935f8a006378fd964349e3062a0d752068ce7b225a31c446f0d96468dc55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e14e935f8a006378fd964349e3062a0d752068ce7b225a31c446f0d96468dc55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e14e935f8a006378fd964349e3062a0d752068ce7b225a31c446f0d96468dc55?s=96&d=mm&r=g\",\"caption\":\"iAfrika\"},\"description\":\"Amaphupho, Amasiko, Izithakazelo, Umlando ngesiZulu. Amaphupha ngesiXhosa: https:\\\/\\\/iafrika.org\\\/xh\",\"url\":\"https:\\\/\\\/iafrika.org\\\/tn\\\/author\\\/iafrika\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ditoro ka ga madi le go tswa madi - iAfrika - Setswana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-madi-le-go-tswa-madi\/","og_locale":"en_US","og_type":"article","og_title":"Ditoro ka ga madi le go tswa madi - iAfrika - Setswana","og_description":"Fa o lora o tswa madi lobaka lo lo leele mme o sa itse gore goreng, go raya gore o tlile go nna le bolwetse jo bo masisi tota gautshwane. Fa madi a o a gotlhola, o tlile go iphitlhela o le ntweng gautshwane. Fa o a tlhatsa madi a, le fa go ntse jalo, ... Read more","og_url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-madi-le-go-tswa-madi\/","og_site_name":"iAfrika - Setswana","article_published_time":"2023-05-20T12:46:47+00:00","article_modified_time":"2023-09-27T10:23:58+00:00","author":"iAfrika","twitter_card":"summary_large_image","twitter_misc":{"Written by":"iAfrika"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-madi-le-go-tswa-madi\/#article","isPartOf":{"@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-madi-le-go-tswa-madi\/"},"author":{"name":"iAfrika","@id":"https:\/\/iafrika.org\/tn\/#\/schema\/person\/55a0587c04707bb054363ee4f50541bb"},"headline":"Ditoro ka ga madi le go tswa madi","datePublished":"2023-05-20T12:46:47+00:00","dateModified":"2023-09-27T10:23:58+00:00","mainEntityOfPage":{"@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-madi-le-go-tswa-madi\/"},"wordCount":71,"commentCount":0,"publisher":{"@id":"https:\/\/iafrika.org\/tn\/#organization"},"keywords":["Madi","Tswa madi"],"articleSection":["Ditoro ka ga Bolwetse","Tlhaloso ya Ditoro"],"inLanguage":"en-ZA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/iafrika.org\/tn\/ditoro-ka-ga-madi-le-go-tswa-madi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-madi-le-go-tswa-madi\/","url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-madi-le-go-tswa-madi\/","name":"Ditoro ka ga madi le go tswa madi - iAfrika - Setswana","isPartOf":{"@id":"https:\/\/iafrika.org\/tn\/#website"},"datePublished":"2023-05-20T12:46:47+00:00","dateModified":"2023-09-27T10:23:58+00:00","breadcrumb":{"@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-madi-le-go-tswa-madi\/#breadcrumb"},"inLanguage":"en-ZA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iafrika.org\/tn\/ditoro-ka-ga-madi-le-go-tswa-madi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-madi-le-go-tswa-madi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/iafrika.org\/tn\/"},{"@type":"ListItem","position":2,"name":"Ditoro ka ga madi le go tswa madi"}]},{"@type":"WebSite","@id":"https:\/\/iafrika.org\/tn\/#website","url":"https:\/\/iafrika.org\/tn\/","name":"iAfrika - Setswana","description":"Tlhaloso ya Ditoro, Maele le diane, Dipoko tsa losika le difane","publisher":{"@id":"https:\/\/iafrika.org\/tn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iafrika.org\/tn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-ZA"},{"@type":"Organization","@id":"https:\/\/iafrika.org\/tn\/#organization","name":"iAfrika - Setswana","url":"https:\/\/iafrika.org\/tn\/","logo":{"@type":"ImageObject","inLanguage":"en-ZA","@id":"https:\/\/iafrika.org\/tn\/#\/schema\/logo\/image\/","url":"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/02\/Fullform_Logo_Primary.png","contentUrl":"https:\/\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/02\/Fullform_Logo_Primary.png","width":800,"height":296,"caption":"iAfrika - Setswana"},"image":{"@id":"https:\/\/iafrika.org\/tn\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/iafrika.org\/tn\/#\/schema\/person\/55a0587c04707bb054363ee4f50541bb","name":"iAfrika","image":{"@type":"ImageObject","inLanguage":"en-ZA","@id":"https:\/\/secure.gravatar.com\/avatar\/e14e935f8a006378fd964349e3062a0d752068ce7b225a31c446f0d96468dc55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e14e935f8a006378fd964349e3062a0d752068ce7b225a31c446f0d96468dc55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e14e935f8a006378fd964349e3062a0d752068ce7b225a31c446f0d96468dc55?s=96&d=mm&r=g","caption":"iAfrika"},"description":"Amaphupho, Amasiko, Izithakazelo, Umlando ngesiZulu. Amaphupha ngesiXhosa: https:\/\/iafrika.org\/xh","url":"https:\/\/iafrika.org\/tn\/author\/iafrika\/"}]}},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":1815,"url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-bolwetse\/","url_meta":{"origin":1794,"position":0},"title":"Ditoro ka ga bolwetse","author":"iAfrika","date":"20 May 2023","format":false,"excerpt":"Fa o lora o na le bolwetse, ka tlwaelo go raya gore o tlile go itekanela. Fa o lora o na le bolwetse jo bo itseng go raya gore mongwe yo mongwe yo o tshwereng ke bolwetse joo o tlile go fola. Fa o lora ka bolwetse go ka nna\u2026","rel":"","context":"In &quot;Ditoro ka ga Bolwetse&quot;","block_context":{"text":"Ditoro ka ga Bolwetse","link":"https:\/\/iafrika.org\/tn\/category\/tlhaloso-ya-ditoro\/ditoro-ka-ga-bolwetse\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2067,"url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-monnamogolo-kgotsa-mosadimogolo\/","url_meta":{"origin":1794,"position":1},"title":"Ditoro ka ga monnamogolo kgotsa mosadimogolo","author":"iAfrika","date":"20 May 2023","format":false,"excerpt":"Fa o lora ka monna yo mogolo kgotsa mosadi yo mogolo, go raya gore mongwe o tlile go go thusa go tswa fa mathateng a o leng fa go one gautshwane. Fa o tlhoka madi, mongwe o tlile go go\u00a0 naya madi a kadimo.","rel":"","context":"In &quot;Ditoro ka ga Batho&quot;","block_context":{"text":"Ditoro ka ga Batho","link":"https:\/\/iafrika.org\/tn\/category\/tlhaloso-ya-ditoro\/ditoro-ka-ga-batho\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1763,"url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-nko\/","url_meta":{"origin":1794,"position":2},"title":"Ditoro ka ga nko","author":"iAfrika","date":"20 May 2023","format":false,"excerpt":"Fa o lora ka nko ya gago, e ka kaya dilo di le dintsi. Fa o lora e se yo, ke sesupo sa \u00a0madimabe kgotsa lona leso (segolobogolo fa e le gore o a lwala). Fa e le gore e kgolo thata, o tlile go nna mohumi fela ga nna\u2026","rel":"","context":"In &quot;Ditoro ka ga mmele&quot;","block_context":{"text":"Ditoro ka ga mmele","link":"https:\/\/iafrika.org\/tn\/category\/tlhaloso-ya-ditoro\/ditoro-ka-ga-mmele\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":764,"url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-botlhole\/","url_meta":{"origin":1794,"position":3},"title":"Ditoro ka ga botlhole","author":"iAfrika","date":"20 May 2023","format":false,"excerpt":"Fa o lora o filwe botlhole, go raya gore o tlile go nna le mathata a madi. Thokomela gore o adima mang madi, o se tsenele dikgaisano dipe mme o netefatse gore o dirisa madi ka botlhale.","rel":"","context":"In &quot;Tlhaloso ya Ditoro&quot;","block_context":{"text":"Tlhaloso ya Ditoro","link":"https:\/\/iafrika.org\/tn\/category\/tlhaloso-ya-ditoro\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/iafrika.org\/tn\/wp-content\/uploads\/sites\/4\/2022\/01\/199988-poison.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2233,"url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-tsheke\/","url_meta":{"origin":1794,"position":4},"title":"Ditoro ka ga t\u0161heke","author":"iAfrika","date":"21 May 2023","format":false,"excerpt":"Fa o lora ka t\u0161heke, go raya gore o tlile go nna le madi go ise go ye kae fela ke tlhagiso gore o e dirise sentle.","rel":"","context":"In &quot;Ditoro ka ga madi le khumo&quot;","block_context":{"text":"Ditoro ka ga madi le khumo","link":"https:\/\/iafrika.org\/tn\/category\/tlhaloso-ya-ditoro\/ditoro-ka-ga-madi-le-khumo\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2265,"url":"https:\/\/iafrika.org\/tn\/ditoro-ka-ga-sejanaga-2\/","url_meta":{"origin":1794,"position":5},"title":"Ditoro ka ga sejanaga","author":"iAfrika","date":"21 May 2023","format":false,"excerpt":"Fa o lora gore o ka fa sejanageng mme mongwe a kgweetsa ka lobelo, go raya gore o tlile go nna lesego wa atlega.\u00a0 Fa e le wena motho yo o kgweetsang, le fa go ntse jalo, o tlile go latlhegelwa ke madi go ise go ye kae","rel":"","context":"In &quot;Ditoro ka ga go eta&quot;","block_context":{"text":"Ditoro ka ga go eta","link":"https:\/\/iafrika.org\/tn\/category\/tlhaloso-ya-ditoro\/ditoro-ka-ga-go-eta\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/posts\/1794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/users\/139"}],"replies":[{"embeddable":true,"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/comments?post=1794"}],"version-history":[{"count":1,"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/posts\/1794\/revisions"}],"predecessor-version":[{"id":1795,"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/posts\/1794\/revisions\/1795"}],"wp:attachment":[{"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/media?parent=1794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/categories?post=1794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iafrika.org\/tn\/wp-json\/wp\/v2\/tags?post=1794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}